{"id":803,"date":"2023-06-05T10:20:47","date_gmt":"2023-06-05T08:20:47","guid":{"rendered":"https:\/\/ethanolpress.de\/blog\/?p=803"},"modified":"2023-06-05T10:20:47","modified_gmt":"2023-06-05T08:20:47","slug":"du-machst-es-moeglich","status":"publish","type":"post","link":"https:\/\/ethanolpress.de\/blog\/2023\/06\/05\/du-machst-es-moeglich\/","title":{"rendered":"Du machst es m\u00f6glich&#8230;"},"content":{"rendered":"\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"640\" data-id=\"804\" src=\"https:\/\/ethanolpress.de\/blog\/wp-content\/uploads\/2023\/06\/20230526_121714.jpg\" alt=\"\" class=\"wp-image-804\" srcset=\"https:\/\/ethanolpress.de\/blog\/wp-content\/uploads\/2023\/06\/20230526_121714.jpg 640w, https:\/\/ethanolpress.de\/blog\/wp-content\/uploads\/2023\/06\/20230526_121714-300x300.jpg 300w, https:\/\/ethanolpress.de\/blog\/wp-content\/uploads\/2023\/06\/20230526_121714-150x150.jpg 150w, https:\/\/ethanolpress.de\/blog\/wp-content\/uploads\/2023\/06\/20230526_121714-100x100.jpg 100w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/><\/figure>\n<\/figure>\n\n\n\n<p>Meine unqualifizierte Kritik. (rolf enskat)<\/p>\n\n\n\n<p>Als vollkommen unmusikalischer Mensch, dem lediglich die Grundelemente wie Takt, Melodie und Text gel\u00e4ufig sind, nehme ich mir dennnoch die Freiheit, deren Wirkung auf mich zu bewerten.<br>Es ist wohl au\u00dfer Zweifel, da\u00df Musik in der Lage ist, Gef\u00fchle zu erzeugen oder zu verst\u00e4rken. Musik und Lieder sind geeignet, eine Stimmung zu verst\u00e4rken, vom bedrohlichen Marsch, lieblichen Kuschelrock, hin\u00fcber zur Trauer und Abgesang des Todes. Und dann die unbedeutende Aufzugmucke und die der Warteschleife.<\/p>\n\n\n\n<p>Da ich gerne mit Gedanken&nbsp; spiele, um meine Umwelt in&nbsp; Schubladen zu stecken, stellte sich mir die Frage, nachdem ich Anjas neuste Komposition (&#8222;Du machst es m\u00f6glich&#8230;&#8220;) h\u00f6rte, ob es auch in der Musik ein<br>Oxymoron (Zusammenstellung zweier sich widersprechender Begriffe in einem Kompositum oder in einer rhetorischen Figur) gibt.<br>Einfacher formuliert: Sind Melodie und Text zwei Komponenten, die sich gegenseitig unterst\u00fctzen und erg\u00e4nzen, oder widersprechen sie sich?<\/p>\n\n\n\n<p>Hierzu habe ich eine Episode meiner Tochter mit folgendem Lied.<br>Text: Wir lagen tr\u00e4umend im Gras, die K\u00f6pfe voll verr\u00fcckter Ideen. Er sagte nur zum Spa\u00df, komm lass uns auf die Reise gehen&#8230;&#8220; (Juliane Werding \/ Der Tag als Johnny Kramer starb).<br>Jahrelang lachte, schunkelte und sang sie den Refrain lustig mit. Ich dachte immer es sei ihre Art von Ironie und Sarkasmus. So war es nicht. Sie hatte nie auf den Text nach der ersten Strophe geachtet. Als ich sie darauf ansprach, war sie peinlich ber\u00fchrt, die Tragik des Liedes nicht erkannt zu haben.<\/p>\n\n\n\n<p>&#8222;Du machst es m\u00f6glich&#8230;&#8220; hat eine warme, kuschelige Melodie, friedlich scheinen die Strahlen in das Gem\u00fct, um es zu erw\u00e4rmen. Doch der Text ist bissig und unbarmherzig. Die Wahrheit ist hier mal anders verpackt, Ironie und Spott.<\/p>\n\n\n\n<p>Eine Taktik, den Gegner mit Fr\u00f6hlichkeit zu verwirren.<br>Es ist wie das Huhn, das dem Belagerer \u00fcber die Mauer zugevorfen wird, &#8222;Schaut, wir haben noch zu essen, wir geben nicht auf!&#8220;<\/p>\n\n\n\n<p>Eine gelungene Zusammenstellung!<\/p>\n\n\n\n<p><a href=\"https:\/\/t.me\/AnjaMusik\/256\" data-type=\"URL\" data-id=\"https:\/\/t.me\/AnjaMusik\/256\">https:\/\/t.me\/AnjaMusik\/256<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Meine unqualifizierte Kritik. (rolf enskat) Als vollkommen unmusikalischer Mensch, dem lediglich die Grundelemente wie Takt, Melodie und Text gel\u00e4ufig sind, nehme ich mir dennnoch die Freiheit, deren Wirkung auf mich zu bewerten.Es ist wohl au\u00dfer Zweifel, da\u00df Musik in der Lage ist, Gef\u00fchle zu erzeugen oder zu verst\u00e4rken. Musik und Lieder sind geeignet, eine Stimmung &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/ethanolpress.de\/blog\/2023\/06\/05\/du-machst-es-moeglich\/\" class=\"more-link\"><span class=\"screen-reader-text\">\u201eDu machst es m\u00f6glich&#8230;\u201c<\/span> weiterlesen<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/ethanolpress.de\/blog\/wp-json\/wp\/v2\/posts\/803"}],"collection":[{"href":"https:\/\/ethanolpress.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ethanolpress.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ethanolpress.de\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ethanolpress.de\/blog\/wp-json\/wp\/v2\/comments?post=803"}],"version-history":[{"count":2,"href":"https:\/\/ethanolpress.de\/blog\/wp-json\/wp\/v2\/posts\/803\/revisions"}],"predecessor-version":[{"id":806,"href":"https:\/\/ethanolpress.de\/blog\/wp-json\/wp\/v2\/posts\/803\/revisions\/806"}],"wp:attachment":[{"href":"https:\/\/ethanolpress.de\/blog\/wp-json\/wp\/v2\/media?parent=803"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ethanolpress.de\/blog\/wp-json\/wp\/v2\/categories?post=803"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ethanolpress.de\/blog\/wp-json\/wp\/v2\/tags?post=803"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}