{"id":521,"date":"2021-07-25T16:07:14","date_gmt":"2021-07-25T14:07:14","guid":{"rendered":"http:\/\/ethanolpress.de\/blog\/?p=521"},"modified":"2021-07-25T16:07:14","modified_gmt":"2021-07-25T14:07:14","slug":"politiker-medien-von-rolf-enskat","status":"publish","type":"post","link":"https:\/\/ethanolpress.de\/blog\/2021\/07\/25\/politiker-medien-von-rolf-enskat\/","title":{"rendered":"Politiker &#038; Medien von Rolf Enskat"},"content":{"rendered":"\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"583\" src=\"https:\/\/ethanolpress.de\/blog\/wp-content\/uploads\/2021\/07\/Screenshot_20210725-140247_Telegram-1024x583.jpg\" alt=\"\" class=\"wp-image-522\" srcset=\"https:\/\/ethanolpress.de\/blog\/wp-content\/uploads\/2021\/07\/Screenshot_20210725-140247_Telegram-1024x583.jpg 1024w, https:\/\/ethanolpress.de\/blog\/wp-content\/uploads\/2021\/07\/Screenshot_20210725-140247_Telegram-300x171.jpg 300w, https:\/\/ethanolpress.de\/blog\/wp-content\/uploads\/2021\/07\/Screenshot_20210725-140247_Telegram-768x437.jpg 768w, https:\/\/ethanolpress.de\/blog\/wp-content\/uploads\/2021\/07\/Screenshot_20210725-140247_Telegram-1536x874.jpg 1536w, https:\/\/ethanolpress.de\/blog\/wp-content\/uploads\/2021\/07\/Screenshot_20210725-140247_Telegram.jpg 1897w\" sizes=\"(max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\" \/><figcaption>Reportage-Team Der Spiegel<\/figcaption><\/figure>\n\n\n\n<p>Sonniger Kindergartentag am Strand<br>&#8220; Hat jetzt JEDER sein F\u00f6rmchen?&#8220;<\/p>\n\n\n\n<p>Auch in den Schulen unter dem Regenbogendach der Inklusion lassen wir kein Kind&nbsp; zur\u00fcck.<\/p>\n\n\n\n<p>So schufen wir einen Pool f\u00fcr Menschen deren Scheitern, ohne fremde Hilfe, unausweichlich w\u00e4re.<\/p>\n\n\n\n<p>Ihre Aufgabenbeschreibung ist: &#8222;Ehrengast, Gr\u00fc\u00dfaugust, Wichtigtuer, Ehrendoktor\u00a0 oder Edelgaffer.&#8220;<br>Zusammengefasst Berufspolitiker.<\/p>\n\n\n\n<p>Wie zum Teufel k\u00f6nnt ihr erwarten, da\u00df diese Menschen in Zeiten der Not sinnvolle Entscheidungen f\u00fcr euch treffen?<\/p>\n\n\n\n<p>\u2606  \u2606 \u2606<\/p>\n\n\n\n<p><strong>Wer hat die <\/strong>Medienhoheit?<br>Unter all dem Leid und N\u00f6ten der betroffenen Menschen findet ein Gerangel um die Medienhoheit statt. In dem Ort Schuld an der Ahr werden Hilfsg\u00fcter im Werte von 7500\u20ac, gespendet von J\u00fcrgen Els\u00e4sser dem Herausgeber des Compact Magazins, verteilt. Ein Reportage-Team des Spiegel hat sich ebenfalls eingefunden, um die Hilfe von &#8222;Rechts&#8220; zu dokumentieren.<br>Diese werden wiederum vom &#8222;Aktivisten Mann&#8220; unter die Lupe genommen.<\/p>\n\n\n\n<p>Die Gesellschaft ist ohne Anstand.<br>Die Gesellschaft ist am Arsch!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sonniger Kindergartentag am Strand&#8220; Hat jetzt JEDER sein F\u00f6rmchen?&#8220; Auch in den Schulen unter dem Regenbogendach der Inklusion lassen wir kein Kind&nbsp; zur\u00fcck. So schufen wir einen Pool f\u00fcr Menschen deren Scheitern, ohne fremde Hilfe, unausweichlich w\u00e4re. Ihre Aufgabenbeschreibung ist: &#8222;Ehrengast, Gr\u00fc\u00dfaugust, Wichtigtuer, Ehrendoktor\u00a0 oder Edelgaffer.&#8220;Zusammengefasst Berufspolitiker. Wie zum Teufel k\u00f6nnt ihr erwarten, da\u00df diese &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/ethanolpress.de\/blog\/2021\/07\/25\/politiker-medien-von-rolf-enskat\/\" class=\"more-link\"><span class=\"screen-reader-text\">\u201ePolitiker &#038; Medien von Rolf Enskat\u201c<\/span> weiterlesen<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/ethanolpress.de\/blog\/wp-json\/wp\/v2\/posts\/521"}],"collection":[{"href":"https:\/\/ethanolpress.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ethanolpress.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ethanolpress.de\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ethanolpress.de\/blog\/wp-json\/wp\/v2\/comments?post=521"}],"version-history":[{"count":1,"href":"https:\/\/ethanolpress.de\/blog\/wp-json\/wp\/v2\/posts\/521\/revisions"}],"predecessor-version":[{"id":523,"href":"https:\/\/ethanolpress.de\/blog\/wp-json\/wp\/v2\/posts\/521\/revisions\/523"}],"wp:attachment":[{"href":"https:\/\/ethanolpress.de\/blog\/wp-json\/wp\/v2\/media?parent=521"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ethanolpress.de\/blog\/wp-json\/wp\/v2\/categories?post=521"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ethanolpress.de\/blog\/wp-json\/wp\/v2\/tags?post=521"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}